{"id":2953,"date":"2019-11-02T13:39:31","date_gmt":"2019-11-02T13:39:31","guid":{"rendered":"https:\/\/dev.uhrwerk-gutach.de\/?page_id=2953"},"modified":"2026-05-04T14:40:08","modified_gmt":"2026-05-04T14:40:08","slug":"jobs","status":"publish","type":"page","link":"https:\/\/uhrwerk-gutach.de\/webers-esszeit\/jobs\/","title":{"rendered":"Stellenanzeigen"},"content":{"rendered":"\n<div class=\"wp-block-uagb-container uagb-block-0d8f05c4 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-b43082df\"><h1 class=\"uagb-heading-text\">STELLENANZEIGEN<\/h1><\/div>\n\n\n\n<p class=\"has-text-align-center has-ast-global-color-5-color has-ffffff-background-color has-text-color has-background has-medium-font-size wp-block-paragraph\">WERDEN SIE TEIL UNSERES TEAMS!<\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-8cf6077c alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-call-to-action uagb-block-4322ae82 wp-block-button\"><div class=\"uagb-cta__wrap\"><h3 class=\"uagb-cta__title\">OFFENE STELLEN<\/h3><p class=\"uagb-cta__desc\">Bewerben Sie sich ganz einfach mit ein paar Klicks!<\/p><\/div><div class=\"uagb-cta__buttons\"><a href=\"https:\/\/uhrwerk-gutach.de\/webers-esszeit\/blitzbewerbung\/\" class=\"uagb-cta__button-link-wrapper wp-block-button__link\" target=\"_self\" rel=\"noopener noreferrer\">BLITZBEWERBUNG<\/a><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:61px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-uagb-faq uagb-faq__outer-wrap uagb-block-3351c502 uagb-faq-icon-row-reverse uagb-faq-layout-accordion uagb-faq-expand-first-false uagb-faq-inactive-other-true uagb-faq__wrap uagb-buttons-layout-wrap uagb-faq-equal-height     \" data-faqtoggle=\"true\" role=\"tablist\"><script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"@id\":\"https:\\\/\\\/uhrwerk-gutach.de\\\/webers-esszeit\\\/jobs\\\/\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"<strong>Konditor mit AEVO oder Meister (m\\\/w\\\/d) Vollzeit<\\\/strong> ab sofort\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<br>\\ud83c\\udf82 Werde Teil unseres Teams \\u2013 Konditor (m\\\/w\\\/d) bei Weber\\u2019 Esszeit<br><strong>Backen ist deine Leidenschaft?<\\\/strong><br>Du liebst es, kreative Ideen umzusetzen und Menschen mit deinen Kreationen zu begeistern? Dann bist du bei uns genau richtig!<br>Bei <strong>Weber\\u2019 Esszeit<\\\/strong> erwartet dich ein junges, engagiertes Team, in dem du deine F\\u00e4higkeiten voll entfalten kannst. Mit deinem handwerklichen K\\u00f6nnen und deiner Kreativit\\u00e4t tr\\u00e4gst du dazu bei, dass jeder Besuch f\\u00fcr unsere G\\u00e4ste zu einem besonderen Erlebnis wird.<br><br>\\ud83e\\uddc1 Deine Aufgaben<br>Herstellung verschiedener Kuchen sowie Sahne- und Cremetorten<br>Anfertigung individueller Torten (Hochzeiten, Kommunionen, Geburtstage, Motivtorten)<br>Modellieren und detailverliebtes Verzieren von Torten<br>Kreation von Desserts f\\u00fcr unser \\u00c0-la-carte-Gesch\\u00e4ft und Veranstaltungen<br>Herstellung unseres hausgemachten Eises<br>Zubereitung herzhafter Backwaren f\\u00fcr unser Fr\\u00fchst\\u00fccksbuffet<br>\\ud83d\\udc49 <strong>Deine Ideen sind ausdr\\u00fccklich erw\\u00fcnscht!<\\\/strong> Bei uns kannst du kreativ mitgestalten.<br><br>\\ud83d\\udc69\\u200d\\ud83c\\udf73 Das bringst du mit<br>Abgeschlossene Ausbildung als Konditor\\\/in<br>AEVO oder Meister w\\u00fcnschenswert<br>Berufserfahrung in der Konditorei und im Dessertbereich<br>Sehr gute Fachkenntnisse und ein hoher Qualit\\u00e4tsanspruch<br>Zuverl\\u00e4ssigkeit, Verantwortungsbewusstsein und Lernbereitschaft<br>Teamgeist, Kreativit\\u00e4t und Leidenschaft f\\u00fcrs Handwerk<br>HACCP-Kenntnisse<br><br>\\u2728 Das erwartet dich bei uns<br>Attraktive Verg\\u00fctung inkl. Sonn-, Feiertags- und Nachtzuschl\\u00e4gen<br>Flexible Arbeitszeiten mit geregelter Freizeit<br>Freizeit auch an Wochenenden<br>Digitale Zeiterfassung &amp; \\u00dcberstundenverg\\u00fctung<br>Sehr gute Aufstiegsm\\u00f6glichkeiten bis zur Backstubenleitung<br>Zusammenarbeit mit motivierten Auszubildenden<br>Ein junges, dynamisches Team mit viel Teamgeist<br>Gro\\u00dfer Gestaltungsspielraum f\\u00fcr deine Ideen<br>Moderner Arbeitsplatz mit neuester Technik<br><br>\\ud83d\\ude80 Klingt nach deinem n\\u00e4chsten Schritt?<br>Dann freuen wir uns darauf, dich kennenzulernen!<br>Werde Teil von Weber\\u2019 Esszeit und bring deine Leidenschaft f\\u00fcrs Backen bei uns ein.<br><br><strong>Was sonst noch wichtig ist:<\\\/strong><br>Wir sind ein Ganzjahresbetrieb mit Arbeit an Sonn- und Feiertagen. Du solltest bereit sein, dich hier mit einzubringen. Daf\\u00fcr hast du frei, wenn andere arbeiten m\\u00fcssen!<br>Nicht von hier? Wir unterst\\u00fctzen dich gerne bei der Wohnungssuche!<br><br><strong>Das klingt echt gut?<\\\/strong><br>Dann \\u00fcberzeuge uns mit deiner Bewerbung per Mail oder Post, dass du der\\\/die Beste f\\u00fcr diesen Job bist!<br><br><br><img width=\\\"600\\\" height=\\\"400\\\" src=\\\"https:\\\/\\\/www.uhrwerk-gutach.de\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Bild-Stellenanzeige-Restaurantkraft-Ersatzbild.png\\\" alt=\\\"Restaurantfachkraft\\\">\"}},{\"@type\":\"Question\",\"name\":\"<strong>Koch (m\\\/w\\\/d) Vollzeit ab sofort<\\\/strong>\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<br><strong>Koch \\\/ K\\u00f6chin (m\\\/w\\\/d) gesucht \\u2013 Vollzeit | Ganzjahresstelle<\\\/strong><br>Kochen ist deine Leidenschaft? Du liebst es, G\\u00e4ste mit kreativen Gerichten zu begeistern und arbeitest gerne im Team?<br>Dann bist du bei uns genau richtig!<br>Wir suchen eine motivierte Pers\\u00f6nlichkeit, die mit uns gemeinsam kulinarische Erlebnisse schafft und unser junges Team bereichert.<br><br><strong>Das erwartet dich bei uns<\\\/strong><br>Attraktive und faire Bezahlung inkl. Sonn-, Feiertags- und Nachtzuschl\\u00e4ge<br>Geregelte Arbeitszeiten ohne Teildienst<br>Flexible Arbeitszeitmodelle mit planbarer Freizeit<br>Digitale Zeiterfassung und transparente \\u00dcberstundenregelung<br>\\u00dcberdurchschnittliche Entwicklungsm\\u00f6glichkeiten und Aufstiegschancen<br>Arbeiten in einem jungen, motivierten und kollegialen Team<br>Raum f\\u00fcr Kreativit\\u00e4t und eigene Ideen<br>Moderner Arbeitsplatz mit hochwertiger, zeitgem\\u00e4\\u00dfer K\\u00fcchentechnik<br>Ganzj\\u00e4hrige Anstellung in einem stabilen Betrieb<br><br><strong>Das bringst du mit<\\\/strong><br>Abgeschlossene Ausbildung als Koch \\\/ K\\u00f6chin<br>Erfahrung in der warmen und kalten K\\u00fcche<br>Gute Fachkenntnisse und Leidenschaft f\\u00fcr deinen Beruf<br>Teamf\\u00e4higkeit, Zuverl\\u00e4ssigkeit und Lernbereitschaft<br>Kreativit\\u00e4t und Freude am Kochen<br>Kenntnisse in HACCP und Hygienevorschriften<br><br><strong>Wichtige Informationen<\\\/strong><br>Unser Betrieb ist ganzj\\u00e4hrig ge\\u00f6ffnet \\u2013 auch an Sonn- und Feiertagen.<br>Daf\\u00fcr erh\\u00e4ltst du bei uns einen fairen Freizeitausgleich, wenn andere arbeiten.<br>Du kommst nicht aus der Region? Kein Problem \\u2013 wir unterst\\u00fctzen dich gerne bei der Wohnungssuche.<br><br><strong>Jetzt bewerben<\\\/strong><br>Du m\\u00f6chtest Teil unseres Teams werden?<br>Dann freuen wir uns auf deine Bewerbung per E-Mail oder Post.<br>\\u00dcberzeuge uns mit deiner Pers\\u00f6nlichkeit \\u2013 wir freuen uns auf dich!<br><br><img width=\\\"600\\\" height=\\\"400\\\" src=\\\"https:\\\/\\\/www.uhrwerk-gutach.de\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Bild-Stellenanzeige-Koch.png\\\" alt=\\\"Koch beim Abschmecken\\\">\"}},{\"@type\":\"Question\",\"name\":\"<strong><strong>K\\u00fcchenhilfe (m\\\/w\\\/d) Vollzeit\\\/Teilzeit ab sofort <\\\/strong><\\\/strong>\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<br>Du packst gerne mit an und f\\u00fchlst dich in der K\\u00fcche wohl?<br>Dann werde Teil unseres Teams und unterst\\u00fctze uns als K\\u00fcchenhilfe (m\\\/w\\\/d)!<br>Ob hinter den Kulissen oder mitten im Geschehen \\u2013 du sorgst daf\\u00fcr, dass in unserer K\\u00fcche alles reibungslos l\\u00e4uft und unser Team sich auf dich verlassen kann.<br><br><strong>Das erwartet dich bei uns<\\\/strong><br>Ein freundliches, motiviertes K\\u00fcchenteam<br>Flexible Arbeitszeiten nach Absprache<br>Faire und p\\u00fcnktliche Bezahlung<br>Moderner Arbeitsplatz in einer professionellen K\\u00fcche<br>Mitarbeit in einem abwechslungsreichen Gastronomiebetrieb<br>Wertsch\\u00e4tzender Umgang und kurze Entscheidungswege<br><br><strong>Deine Aufgaben<\\\/strong><br>Bedienung der Sp\\u00fclmaschine und Reinigung von Geschirr, Besteck und K\\u00fcchenutensilien<br>Unterst\\u00fctzung am Salatposten (Vorbereitung und Anrichten einfacher Speisen)<br>Allgemeine Hilfst\\u00e4tigkeiten in der K\\u00fcche<br>Einhaltung von Hygiene- und Sauberkeitsstandards<br><br><strong>Das bringst du mit<\\\/strong><br>Freude an praktischer Arbeit in der K\\u00fcche<br>Zuverl\\u00e4ssigkeit und Teamf\\u00e4higkeit<br>Sorgf\\u00e4ltige und schnelle Arbeitsweise<br>Belastbarkeit auch in stressigen Situationen<br>Erfahrung in der K\\u00fcche ist von Vorteil, aber kein Muss<br><br><strong>Wichtig zu wissen<\\\/strong><br>Unser Betrieb ist ganzj\\u00e4hrig ge\\u00f6ffnet \\u2013 auch an Sonn- und Feiertagen.<br>Die Arbeitszeiten werden flexibel im Team abgestimmt.<br><br><strong>Jetzt bewerben<\\\/strong><br>Du hast Lust, unser K\\u00fcchenteam zu unterst\\u00fctzen?<br>Dann freuen wir uns auf deine Bewerbung per E-Mail oder Post!<br><br><br><img width=\\\"600\\\" height=\\\"400\\\" src=\\\"https:\\\/\\\/www.uhrwerk-gutach.de\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Bild-Stellenanzeige-Restaurantkraft-Ersatzbild.png\\\" alt=\\\"Restaurantfachkraft\\\">\"}},{\"@type\":\"Question\",\"name\":\"<strong>Thekenleitung (m\\\/w\\\/d) Vollzeit ab sofort<\\\/strong>\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<br><strong>Leitung Theke (m\\\/w\\\/d) \\u2013 \\u00dcbernimm Verantwortung &amp; gestalte mit uns!<\\\/strong><br>Du m\\u00f6chtest den n\\u00e4chsten Schritt gehen und deine eigene Abteilung f\\u00fchren?<br>Du liebst Gastronomie, arbeitest gerne im Team und willst wirklich etwas bewegen?<br><strong>Dann bist du bei uns genau richtig.<\\\/strong><br><br><strong>Was dich bei uns erwartet<\\\/strong><br>Mehr als nur ein Job \\u2013 wir bieten dir ein Umfeld, in dem du dich wohlf\\u00fchlen und weiterentwickeln kannst:<br>\\ud83e\\udd1d Ein herzliches, motiviertes Team mit starkem Zusammenhalt<br>\\ud83d\\udcc5 Ganzj\\u00e4hrige Anstellung mit <strong>flexiblen Arbeitszeiten<\\\/strong> (kein Teildienst)<br>\\ud83d\\udcbb Ein moderner Arbeitsplatz mit neuester Technik<br>\\ud83d\\udcb0 <strong>\\u00dcberdurchschnittliche Bezahlung<\\\/strong><br>\\ud83c\\udf7d\\ufe0f G\\u00fcnstiges Mitarbeiteressen<br>\\ud83d\\ude80 Raum f\\u00fcr deine Ideen &amp; echte Entwicklungsm\\u00f6glichkeiten<br><br><strong>Deine Aufgaben<\\\/strong><br>In deiner Rolle \\u00fcbernimmst du Verantwortung und gestaltest aktiv mit:<br>F\\u00fchrung und Motivation des Theken-Teams (inkl. Lehrlinge &amp; Praktikant:innen)<br>Zubereitung von warmen und kalten Getr\\u00e4nken auf h\\u00f6chstem Niveau<br>Anrichten und Pr\\u00e4sentation von Desserts<br>Ausgabe unseres hausgemachten Eises am Eisfenster<br>Schneiden und Pr\\u00e4sentieren von Kuchen &amp; Torten<br>Erstellung fairer und effizienter Dienstpl\\u00e4ne<br>Sicherstellung von Sauberkeit &amp; Einhaltung aller Hygienestandards<br>Enge Zusammenarbeit mit Service, Konditorei, K\\u00fcche und Administration<br><br><strong>Das bringst du mit<\\\/strong><br>Abgeschlossene Ausbildung im Gastronomiebereich (Service)<br>Leidenschaft f\\u00fcr deinen Beruf sowie Teamgeist &amp; Kreativit\\u00e4t<br>Freundliches, professionelles Auftreten gegen\\u00fcber G\\u00e4sten und Kolleg:innen<br>Selbstst\\u00e4ndige und strukturierte Arbeitsweise<br>Grundkenntnisse in EDV (z. B. Kassensysteme, Reservierungstools)<br>Gute Deutschkenntnisse sowie Englisch-Grundkenntnisse<br><br><strong>Gut zu wissen<\\\/strong><br>Wir sind ein Ganzjahresbetrieb \\u2013 dazu geh\\u00f6rt auch Arbeit an Sonn- und Feiertagen<br>Daf\\u00fcr genie\\u00dft du deine freien Tage, wenn andere arbeiten<br>Du kommst nicht aus der Region? <strong>Wir unterst\\u00fctzen dich gerne bei der Wohnungssuche<\\\/strong><br><br><strong>Klingt nach deinem n\\u00e4chsten Schritt?<\\\/strong><br>Dann freuen wir uns auf deine Bewerbung!<br>\\u00dcberzeuge uns, warum genau du die perfekte Besetzung f\\u00fcr diese Position bist.<br>\\ud83d\\udce9 <strong>Jetzt bewerben per E-Mail oder Post<\\\/strong><br><br><img width=\\\"600\\\" height=\\\"400\\\" src=\\\"https:\\\/\\\/www.uhrwerk-gutach.de\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Bild-Stellenanzeige-Restaurantkraft-Ersatzbild.png\\\" alt=\\\"Restaurantfachkraft\\\">\"}},{\"@type\":\"Question\",\"name\":\"<strong>MINIJOBBER Sch\\u00fcler 16-17 Jahre  - (w\\\/m\\\/d) - 603-Euro-Basis<\\\/strong> <strong>Foodrunner<\\\/strong> <strong>ab sofort<\\\/strong>\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<br><strong>Mit uns brauchst du kein Fitnessstudio \\u2013 wir sorgen f\\u00fcr deine Bewegung!<\\\/strong><br>Du hast neben Schule oder Studium noch etwas Zeit und suchst einen flexiblen Minijob in der Gastronomie?<br>Dann bist du bei uns genau richtig!<br>Werde Teil unseres Teams und unterst\\u00fctze uns als Foodrunner (m\\\/w\\\/d) im Service.<br><br><strong>Das erwartet dich bei uns<\\\/strong><br>Arbeiten in einem motivierten, herzlichen und engagierten Team<br>Flexible Arbeitszeiten \\u2013 wir nehmen R\\u00fccksicht auf deine privaten Pl\\u00e4ne<br>Moderner Arbeitsplatz mit neuester Technik<br>Unterst\\u00fctzung durch Serviceroboter im Service<br>Mitarbeiterverpflegung zu fairen Konditionen<br>Ein abwechslungsreicher Job mit Bewegung und direktem G\\u00e4stekontakt<br><br><strong>Das bringst du mit<\\\/strong><br>Freude am Umgang mit G\\u00e4sten und ein freundliches Auftreten<br>Teamf\\u00e4higkeit, Zuverl\\u00e4ssigkeit und eine selbstst\\u00e4ndige Arbeitsweise<br>Optional erste Erfahrung in der Gastronomie (kein Muss!)<br>Gute Deutschkenntnisse in Wort und Schrift<br>Grundkenntnisse in Englisch von Vorteil<br>Mindestalter: 16 Jahre<br><br><strong>Wichtig zu wissen<\\\/strong><br>Unser Betrieb ist ganzj\\u00e4hrig ge\\u00f6ffnet \\u2013 auch an Sonn- und Feiertagen.<br>Daf\\u00fcr erwarten wir Bereitschaft zur Mitarbeit an diesen Tagen.<br><br><strong>Jetzt bewerben<\\\/strong><br>Du hast Lust auf einen abwechslungsreichen Job mit Bewegung und Teamspirit?<br>Dann freuen wir uns auf deine Bewerbung per E-Mail oder Post!<br>\\u00dcberzeuge uns \\u2013 wir freuen uns auf dich!<br><br><img width=\\\"600\\\" height=\\\"400\\\" src=\\\"https:\\\/\\\/www.uhrwerk-gutach.de\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Bild-Stellenanzeige-Restaurantkraft-Ersatzbild.png\\\" alt=\\\"Restaurantfachkraft\\\">\"}},{\"@type\":\"Question\",\"name\":\"<strong>\\u00dcBERBR\\u00dcCKUNGSJAHR - f\\u00fcr Abiturienten in Voll- und Teilzeit - Service - individuelle Dauer (6-12 Monate) - 2026<\\\/strong>\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<strong>\\u00dcberbr\\u00fcckungsjob nach dem Abitur (m\\\/w\\\/d) \\u2013 Vollzeit \\\/ Teilzeit<\\\/strong><br><strong>Nach der Schule noch nichts vor? Dann \\u00fcberbr\\u00fccke deine Zeit bis zum n\\u00e4chsten Semester bei uns!<\\\/strong><br>Du hast dein Abitur in der Tasche und m\\u00f6chtest die Zeit sinnvoll nutzen, Geld verdienen und erste Berufserfahrung in der Gastronomie sammeln?<br>Dann bist du bei uns genau richtig!<br>Wir bieten dir einen abwechslungsreichen Job in einem motivierten Team \\u2013 perfekt als \\u00dcberbr\\u00fcckung bis Studium, Ausbildung oder Reise.<br><br><strong>Das erwartet dich bei uns<\\\/strong><br>Arbeiten in einem engagierten, freundlichen Team<br>Flexible Arbeitszeiten<br>Moderner Arbeitsplatz mit neuester Technik<br>\\u00dcberdurchschnittliche Bezahlung<br>Mitarbeiterverpflegung zu kleinen Preisen<br>Raum f\\u00fcr eigene Ideen und aktive Mitgestaltung<br>Ein spannender Job mit Einblick in die Gastronomie<br><br><strong>Das bringst du mit<\\\/strong><br>Erste Erfahrung in der Gastronomie (Service oder Theke) von Vorteil<br>Teamf\\u00e4higkeit, Zuverl\\u00e4ssigkeit und Kreativit\\u00e4t<br>Freundliches und professionelles Auftreten gegen\\u00fcber G\\u00e4sten, Kollegen und Lieferanten<br>Selbstst\\u00e4ndige und strukturierte Arbeitsweise<br>EDV-Kenntnisse (z. B. Tabletkasse, digitales Reservierungssystem)<br>Gute Deutschkenntnisse in Wort und Schrift<br>Grundkenntnisse in Englisch<br><br><strong>Wichtig zu wissen<\\\/strong><br>Unser Betrieb ist ganzj\\u00e4hrig ge\\u00f6ffnet \\u2013 auch an Sonn- und Feiertagen.<br>Daf\\u00fcr bieten wir dir einen fairen Freizeitausgleich, wenn andere arbeiten.<br><br><strong>Jetzt bewerben<\\\/strong><br>Du m\\u00f6chtest die Zeit nach dem Abi sinnvoll nutzen und Teil unseres Teams werden?<br>Dann freuen wir uns auf deine Bewerbung per E-Mail oder Post!<br>\\u00dcberzeuge uns mit deiner Pers\\u00f6nlichkeit \\u2013 wir freuen uns auf dich!<br><br><img width=\\\"600\\\" height=\\\"400\\\" src=\\\"https:\\\/\\\/www.uhrwerk-gutach.de\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Bild-Stellenanzeige-Restaurantkraft-Ersatzbild.png\\\" alt=\\\"Restaurantfachkraft\\\">\"}},{\"@type\":\"Question\",\"name\":\"<strong>AUSZUBILDENDE - als Fachkraft f\\u00fcr Restaurants und Veranstaltungsgastronomie (w\\\/m\\\/d) zum 01.09.202<\\\/strong>7\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<br><strong>Wie viele Gl\\u00e4ser kannst du balancieren? Finde es heraus als unser\\\/e Auszubildende\\\/r<strong> Fachkraft f\\u00fcr Restaurants und Veranstaltungsgastronomie<\\\/strong>!<\\\/strong><br><br>Wir sind t\\u00e4glich mit Feuereifer bei der Sache, lieben es Gastgeber zu sein und haben einen hohen Anspruch an uns selbst. Dabei ist uns wichtig, dass jeder, der Teil von unserem Team wird, Leidenschaft, Herzlichkeit, Anspruch und Echtheit lebt. Wir freuen uns, dich in unserem Team aufzunehmen und dir alles zu zeigen, damit auch du ein\\\/e gute\\\/r Gastgeber\\\/in wirst!<br><br><strong>Mehr als nur ein Ausbildungsplatz - das lernst du bei uns:<\\\/strong><br>- Bedienung und Bewirtung von G\\u00e4sten, zuvorkommender Service steht dabei im Vordergrund<br>- Bedienung des Kassensystems<br>- Beratung der G\\u00e4ste zum Essensangebot und die Auskunft zu verschiedenen Nahrungsmitteln und Getr\\u00e4nken<br>- Zusammenstellung und Gestaltung von Speisekarten und Angeboten<br>- Beratung von Kunden bei der Planung ihrer Festlichkeiten und Veranstaltungen und deren Ausrichtung<br>- Vorbereitung und Dekoration von R\\u00e4umlichkeiten und Einrichtungen<br>- Zubereitung kleinerer Speisen und Getr\\u00e4nke<br>- F\\u00fchrung der eigenen Station<br>- Organisation des eigenen Serviceablaufs<br><br><strong>Du wirst unsere Geheimzutat: - Das bringst du mit:<\\\/strong><br>- Mindestens Guter Hauptschulabschluss oder Mittlere Reife<br>- Gute Leistungen in Mathematik, Deutsch und Englisch<br>- Teamf\\u00e4higkeit und Kreativit\\u00e4t<br>- Organisationstalent<br>- Schnelle Auffassungsgabe und Verwantwortungsbewusstsein<br><br><strong>Was sonst noch wichtig ist:<\\\/strong><br>Wir sind ein Ganzjahresbetrieb mit Arbeit an Sonn- und Feiertagen. Du solltest bereit sein, dich hier mit einzubringen. Daf\\u00fcr hast du frei, wenn andere arbeiten m\\u00fcssen!<br>Nicht von hier? Wir unterst\\u00fctzen dich gerne bei der Wohnungssuche!<br><br><strong>Das klingt echt gut?<\\\/strong><br>Dann \\u00fcberzeuge uns mit deiner Bewerbung per Mail oder Post, dass du der\\\/die Beste f\\u00fcr diesen Job bist!<br><br><img width=\\\"600\\\" height=\\\"400\\\" src=\\\"https:\\\/\\\/www.uhrwerk-gutach.de\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Bild-Stellenanzeige-Azubi-Restaurantfachfrau.png\\\" alt=\\\"Portrait Restaurantleiterin\\\">\"}},{\"@type\":\"Question\",\"name\":\"<strong>AUSZUBILDENDER KOCH (w\\\/m\\\/d) zum 01.09.2027<\\\/strong>\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<br><strong>Werde zum Lebensmittelk\\u00fcnstler! Mach bei uns eine Ausbildung zum Koch (m\\\/w\\\/d)<\\\/strong><br><br>Wir lieben gutes Essen und du lernst dieses zuzubereiten!<br><br><strong>Mehr als nur ein Ausbildungsplatz - das lernst du bei uns:<\\\/strong><br>- Kochen, Braten, D\\u00fcnsten, Flambieren, Marinieren, Garnieren und Filetieren<br>- Anrichten, Abschmecken und Arrangieren von Speisen<br>- Einkauf und fachgerechte Lagerung von Lebensmitteln<br>- Warenkunde, Qualit\\u00e4tskontrolle, Kalkulation<br><br><strong>Du wirst unsere Geheimzutat: - Das bringst du mit:<\\\/strong><br>- Mindestens Guter Hauptschulabschluss oder Mittlere Reife<br>- Gute Leistungen in Mathematik, Deutsch und Englisch<br>- Teamf\\u00e4higkeit und Kreativit\\u00e4t<br>- Organisationstalent<br>- Schnelle Auffassungsgabe und Verwantwortungsbewusstsein<br>- Freude und Interesse an Arbeiten in der K\\u00fcche<br><br><strong>Was sonst noch wichtig ist:<\\\/strong> <br>Wir sind ein Ganzjahresbetrieb mit Arbeit an Sonn- und Feiertagen. Du solltest bereit sein, dich hier mit einzubringen. Daf\\u00fcr hast du frei, wenn andere arbeiten m\\u00fcssen!<br>Nicht von hier? Wir unterst\\u00fctzen dich gerne bei der Wohnungssuche!<br><br><strong>Das klingt echt gut?<\\\/strong><br>Dann \\u00fcberzeuge uns mit deiner Bewerbung per Mail oder Post, dass du der\\\/die Beste f\\u00fcr diesen Job bist!<br><br><img width=\\\"600\\\" height=\\\"400\\\" src=\\\"https:\\\/\\\/www.uhrwerk-gutach.de\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Bild-Stellenanzeige-Koch.png\\\" alt=\\\"Koch beim Abschmecken\\\">\"}}]}<\/script><div class=\"wp-block-uagb-faq-child uagb-faq-child__outer-wrap uagb-faq-item uagb-block-4ce46e18 \" role=\"tab\" tabindex=\"0\"><div class=\"uagb-faq-questions-button uagb-faq-questions\">\t\t\t<span class=\"uagb-icon uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M432 256c0 17.69-14.33 32.01-32 32.01H256v144c0 17.69-14.33 31.99-32 31.99s-32-14.3-32-31.99v-144H48c-17.67 0-32-14.32-32-32.01s14.33-31.99 32-31.99H192v-144c0-17.69 14.33-32.01 32-32.01s32 14.32 32 32.01v144h144C417.7 224 432 238.3 432 256z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"uagb-icon-active uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M400 288h-352c-17.69 0-32-14.32-32-32.01s14.31-31.99 32-31.99h352c17.69 0 32 14.3 32 31.99S417.7 288 400 288z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t<span class=\"uagb-question\"><strong>Konditor mit AEVO oder Meister (m\/w\/d) Vollzeit<\/strong> ab sofort<\/span><\/div><div class=\"uagb-faq-content\"><p><br>\ud83c\udf82 Werde Teil unseres Teams \u2013 Konditor (m\/w\/d) bei Weber\u2019 Esszeit<br><strong>Backen ist deine Leidenschaft?<\/strong><br>Du liebst es, kreative Ideen umzusetzen und Menschen mit deinen Kreationen zu begeistern? Dann bist du bei uns genau richtig!<br>Bei <strong>Weber\u2019 Esszeit<\/strong> erwartet dich ein junges, engagiertes Team, in dem du deine F\u00e4higkeiten voll entfalten kannst. Mit deinem handwerklichen K\u00f6nnen und deiner Kreativit\u00e4t tr\u00e4gst du dazu bei, dass jeder Besuch f\u00fcr unsere G\u00e4ste zu einem besonderen Erlebnis wird.<br><br>\ud83e\uddc1 Deine Aufgaben<br>Herstellung verschiedener Kuchen sowie Sahne- und Cremetorten<br>Anfertigung individueller Torten (Hochzeiten, Kommunionen, Geburtstage, Motivtorten)<br>Modellieren und detailverliebtes Verzieren von Torten<br>Kreation von Desserts f\u00fcr unser \u00c0-la-carte-Gesch\u00e4ft und Veranstaltungen<br>Herstellung unseres hausgemachten Eises<br>Zubereitung herzhafter Backwaren f\u00fcr unser Fr\u00fchst\u00fccksbuffet<br>\ud83d\udc49 <strong>Deine Ideen sind ausdr\u00fccklich erw\u00fcnscht!<\/strong> Bei uns kannst du kreativ mitgestalten.<br><br>\ud83d\udc69\u200d\ud83c\udf73 Das bringst du mit<br>Abgeschlossene Ausbildung als Konditor\/in<br>AEVO oder Meister w\u00fcnschenswert<br>Berufserfahrung in der Konditorei und im Dessertbereich<br>Sehr gute Fachkenntnisse und ein hoher Qualit\u00e4tsanspruch<br>Zuverl\u00e4ssigkeit, Verantwortungsbewusstsein und Lernbereitschaft<br>Teamgeist, Kreativit\u00e4t und Leidenschaft f\u00fcrs Handwerk<br>HACCP-Kenntnisse<br><br>\u2728 Das erwartet dich bei uns<br>Attraktive Verg\u00fctung inkl. Sonn-, Feiertags- und Nachtzuschl\u00e4gen<br>Flexible Arbeitszeiten mit geregelter Freizeit<br>Freizeit auch an Wochenenden<br>Digitale Zeiterfassung &amp; \u00dcberstundenverg\u00fctung<br>Sehr gute Aufstiegsm\u00f6glichkeiten bis zur Backstubenleitung<br>Zusammenarbeit mit motivierten Auszubildenden<br>Ein junges, dynamisches Team mit viel Teamgeist<br>Gro\u00dfer Gestaltungsspielraum f\u00fcr deine Ideen<br>Moderner Arbeitsplatz mit neuester Technik<br><br>\ud83d\ude80 Klingt nach deinem n\u00e4chsten Schritt?<br>Dann freuen wir uns darauf, dich kennenzulernen!<br>Werde Teil von Weber\u2019 Esszeit und bring deine Leidenschaft f\u00fcrs Backen bei uns ein.<br><br><strong>Was sonst noch wichtig ist:<\/strong><br>Wir sind ein Ganzjahresbetrieb mit Arbeit an Sonn- und Feiertagen. Du solltest bereit sein, dich hier mit einzubringen. Daf\u00fcr hast du frei, wenn andere arbeiten m\u00fcssen!<br>Nicht von hier? Wir unterst\u00fctzen dich gerne bei der Wohnungssuche!<br><br><strong>Das klingt echt gut?<\/strong><br>Dann \u00fcberzeuge uns mit deiner Bewerbung per Mail oder Post, dass du der\/die Beste f\u00fcr diesen Job bist!<br><br><br><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.uhrwerk-gutach.de\/wp-content\/uploads\/2021\/01\/Bild-Stellenanzeige-Restaurantkraft-Ersatzbild.png\" alt=\"Restaurantfachkraft\"><\/p><\/div><\/div><div class=\"wp-block-uagb-faq-child uagb-faq-child__outer-wrap uagb-faq-item uagb-block-afa7d999 \" role=\"tab\" tabindex=\"0\"><div class=\"uagb-faq-questions-button uagb-faq-questions\">\t\t\t<span class=\"uagb-icon uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M432 256c0 17.69-14.33 32.01-32 32.01H256v144c0 17.69-14.33 31.99-32 31.99s-32-14.3-32-31.99v-144H48c-17.67 0-32-14.32-32-32.01s14.33-31.99 32-31.99H192v-144c0-17.69 14.33-32.01 32-32.01s32 14.32 32 32.01v144h144C417.7 224 432 238.3 432 256z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"uagb-icon-active uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M400 288h-352c-17.69 0-32-14.32-32-32.01s14.31-31.99 32-31.99h352c17.69 0 32 14.3 32 31.99S417.7 288 400 288z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t<span class=\"uagb-question\"><strong>Koch (m\/w\/d) Vollzeit ab sofort<\/strong><\/span><\/div><div class=\"uagb-faq-content\"><p><br><strong>Koch \/ K\u00f6chin (m\/w\/d) gesucht \u2013 Vollzeit | Ganzjahresstelle<\/strong><br>Kochen ist deine Leidenschaft? Du liebst es, G\u00e4ste mit kreativen Gerichten zu begeistern und arbeitest gerne im Team?<br>Dann bist du bei uns genau richtig!<br>Wir suchen eine motivierte Pers\u00f6nlichkeit, die mit uns gemeinsam kulinarische Erlebnisse schafft und unser junges Team bereichert.<br><br><strong>Das erwartet dich bei uns<\/strong><br>Attraktive und faire Bezahlung inkl. Sonn-, Feiertags- und Nachtzuschl\u00e4ge<br>Geregelte Arbeitszeiten ohne Teildienst<br>Flexible Arbeitszeitmodelle mit planbarer Freizeit<br>Digitale Zeiterfassung und transparente \u00dcberstundenregelung<br>\u00dcberdurchschnittliche Entwicklungsm\u00f6glichkeiten und Aufstiegschancen<br>Arbeiten in einem jungen, motivierten und kollegialen Team<br>Raum f\u00fcr Kreativit\u00e4t und eigene Ideen<br>Moderner Arbeitsplatz mit hochwertiger, zeitgem\u00e4\u00dfer K\u00fcchentechnik<br>Ganzj\u00e4hrige Anstellung in einem stabilen Betrieb<br><br><strong>Das bringst du mit<\/strong><br>Abgeschlossene Ausbildung als Koch \/ K\u00f6chin<br>Erfahrung in der warmen und kalten K\u00fcche<br>Gute Fachkenntnisse und Leidenschaft f\u00fcr deinen Beruf<br>Teamf\u00e4higkeit, Zuverl\u00e4ssigkeit und Lernbereitschaft<br>Kreativit\u00e4t und Freude am Kochen<br>Kenntnisse in HACCP und Hygienevorschriften<br><br><strong>Wichtige Informationen<\/strong><br>Unser Betrieb ist ganzj\u00e4hrig ge\u00f6ffnet \u2013 auch an Sonn- und Feiertagen.<br>Daf\u00fcr erh\u00e4ltst du bei uns einen fairen Freizeitausgleich, wenn andere arbeiten.<br>Du kommst nicht aus der Region? Kein Problem \u2013 wir unterst\u00fctzen dich gerne bei der Wohnungssuche.<br><br><strong>Jetzt bewerben<\/strong><br>Du m\u00f6chtest Teil unseres Teams werden?<br>Dann freuen wir uns auf deine Bewerbung per E-Mail oder Post.<br>\u00dcberzeuge uns mit deiner Pers\u00f6nlichkeit \u2013 wir freuen uns auf dich!<br><br><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.uhrwerk-gutach.de\/wp-content\/uploads\/2021\/01\/Bild-Stellenanzeige-Koch.png\" alt=\"Koch beim Abschmecken\"><\/p><\/div><\/div><div class=\"wp-block-uagb-faq-child uagb-faq-child__outer-wrap uagb-faq-item uagb-block-4b659c8f \" role=\"tab\" tabindex=\"0\"><div class=\"uagb-faq-questions-button uagb-faq-questions\">\t\t\t<span class=\"uagb-icon uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M432 256c0 17.69-14.33 32.01-32 32.01H256v144c0 17.69-14.33 31.99-32 31.99s-32-14.3-32-31.99v-144H48c-17.67 0-32-14.32-32-32.01s14.33-31.99 32-31.99H192v-144c0-17.69 14.33-32.01 32-32.01s32 14.32 32 32.01v144h144C417.7 224 432 238.3 432 256z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"uagb-icon-active uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M400 288h-352c-17.69 0-32-14.32-32-32.01s14.31-31.99 32-31.99h352c17.69 0 32 14.3 32 31.99S417.7 288 400 288z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t<span class=\"uagb-question\"><strong><strong>K\u00fcchenhilfe (m\/w\/d) Vollzeit\/Teilzeit ab sofort <\/strong><\/strong><\/span><\/div><div class=\"uagb-faq-content\"><p><br>Du packst gerne mit an und f\u00fchlst dich in der K\u00fcche wohl?<br>Dann werde Teil unseres Teams und unterst\u00fctze uns als K\u00fcchenhilfe (m\/w\/d)!<br>Ob hinter den Kulissen oder mitten im Geschehen \u2013 du sorgst daf\u00fcr, dass in unserer K\u00fcche alles reibungslos l\u00e4uft und unser Team sich auf dich verlassen kann.<br><br><strong>Das erwartet dich bei uns<\/strong><br>Ein freundliches, motiviertes K\u00fcchenteam<br>Flexible Arbeitszeiten nach Absprache<br>Faire und p\u00fcnktliche Bezahlung<br>Moderner Arbeitsplatz in einer professionellen K\u00fcche<br>Mitarbeit in einem abwechslungsreichen Gastronomiebetrieb<br>Wertsch\u00e4tzender Umgang und kurze Entscheidungswege<br><br><strong>Deine Aufgaben<\/strong><br>Bedienung der Sp\u00fclmaschine und Reinigung von Geschirr, Besteck und K\u00fcchenutensilien<br>Unterst\u00fctzung am Salatposten (Vorbereitung und Anrichten einfacher Speisen)<br>Allgemeine Hilfst\u00e4tigkeiten in der K\u00fcche<br>Einhaltung von Hygiene- und Sauberkeitsstandards<br><br><strong>Das bringst du mit<\/strong><br>Freude an praktischer Arbeit in der K\u00fcche<br>Zuverl\u00e4ssigkeit und Teamf\u00e4higkeit<br>Sorgf\u00e4ltige und schnelle Arbeitsweise<br>Belastbarkeit auch in stressigen Situationen<br>Erfahrung in der K\u00fcche ist von Vorteil, aber kein Muss<br><br><strong>Wichtig zu wissen<\/strong><br>Unser Betrieb ist ganzj\u00e4hrig ge\u00f6ffnet \u2013 auch an Sonn- und Feiertagen.<br>Die Arbeitszeiten werden flexibel im Team abgestimmt.<br><br><strong>Jetzt bewerben<\/strong><br>Du hast Lust, unser K\u00fcchenteam zu unterst\u00fctzen?<br>Dann freuen wir uns auf deine Bewerbung per E-Mail oder Post!<br><br><br><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.uhrwerk-gutach.de\/wp-content\/uploads\/2021\/01\/Bild-Stellenanzeige-Restaurantkraft-Ersatzbild.png\" alt=\"Restaurantfachkraft\"><\/p><\/div><\/div><div class=\"wp-block-uagb-faq-child uagb-faq-child__outer-wrap uagb-faq-item uagb-block-f5eb03da \" role=\"tab\" tabindex=\"0\"><div class=\"uagb-faq-questions-button uagb-faq-questions\">\t\t\t<span class=\"uagb-icon uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M432 256c0 17.69-14.33 32.01-32 32.01H256v144c0 17.69-14.33 31.99-32 31.99s-32-14.3-32-31.99v-144H48c-17.67 0-32-14.32-32-32.01s14.33-31.99 32-31.99H192v-144c0-17.69 14.33-32.01 32-32.01s32 14.32 32 32.01v144h144C417.7 224 432 238.3 432 256z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"uagb-icon-active uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M400 288h-352c-17.69 0-32-14.32-32-32.01s14.31-31.99 32-31.99h352c17.69 0 32 14.3 32 31.99S417.7 288 400 288z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t<span class=\"uagb-question\"><strong>Thekenleitung (m\/w\/d) Vollzeit ab sofort<\/strong><\/span><\/div><div class=\"uagb-faq-content\"><p><br><strong>Leitung Theke (m\/w\/d) \u2013 \u00dcbernimm Verantwortung &amp; gestalte mit uns!<\/strong><br>Du m\u00f6chtest den n\u00e4chsten Schritt gehen und deine eigene Abteilung f\u00fchren?<br>Du liebst Gastronomie, arbeitest gerne im Team und willst wirklich etwas bewegen?<br><strong>Dann bist du bei uns genau richtig.<\/strong><br><br><strong>Was dich bei uns erwartet<\/strong><br>Mehr als nur ein Job \u2013 wir bieten dir ein Umfeld, in dem du dich wohlf\u00fchlen und weiterentwickeln kannst:<br>\ud83e\udd1d Ein herzliches, motiviertes Team mit starkem Zusammenhalt<br>\ud83d\udcc5 Ganzj\u00e4hrige Anstellung mit <strong>flexiblen Arbeitszeiten<\/strong> (kein Teildienst)<br>\ud83d\udcbb Ein moderner Arbeitsplatz mit neuester Technik<br>\ud83d\udcb0 <strong>\u00dcberdurchschnittliche Bezahlung<\/strong><br>\ud83c\udf7d\ufe0f G\u00fcnstiges Mitarbeiteressen<br>\ud83d\ude80 Raum f\u00fcr deine Ideen &amp; echte Entwicklungsm\u00f6glichkeiten<br><br><strong>Deine Aufgaben<\/strong><br>In deiner Rolle \u00fcbernimmst du Verantwortung und gestaltest aktiv mit:<br>F\u00fchrung und Motivation des Theken-Teams (inkl. Lehrlinge &amp; Praktikant:innen)<br>Zubereitung von warmen und kalten Getr\u00e4nken auf h\u00f6chstem Niveau<br>Anrichten und Pr\u00e4sentation von Desserts<br>Ausgabe unseres hausgemachten Eises am Eisfenster<br>Schneiden und Pr\u00e4sentieren von Kuchen &amp; Torten<br>Erstellung fairer und effizienter Dienstpl\u00e4ne<br>Sicherstellung von Sauberkeit &amp; Einhaltung aller Hygienestandards<br>Enge Zusammenarbeit mit Service, Konditorei, K\u00fcche und Administration<br><br><strong>Das bringst du mit<\/strong><br>Abgeschlossene Ausbildung im Gastronomiebereich (Service)<br>Leidenschaft f\u00fcr deinen Beruf sowie Teamgeist &amp; Kreativit\u00e4t<br>Freundliches, professionelles Auftreten gegen\u00fcber G\u00e4sten und Kolleg:innen<br>Selbstst\u00e4ndige und strukturierte Arbeitsweise<br>Grundkenntnisse in EDV (z. B. Kassensysteme, Reservierungstools)<br>Gute Deutschkenntnisse sowie Englisch-Grundkenntnisse<br><br><strong>Gut zu wissen<\/strong><br>Wir sind ein Ganzjahresbetrieb \u2013 dazu geh\u00f6rt auch Arbeit an Sonn- und Feiertagen<br>Daf\u00fcr genie\u00dft du deine freien Tage, wenn andere arbeiten<br>Du kommst nicht aus der Region? <strong>Wir unterst\u00fctzen dich gerne bei der Wohnungssuche<\/strong><br><br><strong>Klingt nach deinem n\u00e4chsten Schritt?<\/strong><br>Dann freuen wir uns auf deine Bewerbung!<br>\u00dcberzeuge uns, warum genau du die perfekte Besetzung f\u00fcr diese Position bist.<br>\ud83d\udce9 <strong>Jetzt bewerben per E-Mail oder Post<\/strong><br><br><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.uhrwerk-gutach.de\/wp-content\/uploads\/2021\/01\/Bild-Stellenanzeige-Restaurantkraft-Ersatzbild.png\" alt=\"Restaurantfachkraft\"><\/p><\/div><\/div><div class=\"wp-block-uagb-faq-child uagb-faq-child__outer-wrap uagb-faq-item uagb-block-903c847d \" role=\"tab\" tabindex=\"0\"><div class=\"uagb-faq-questions-button uagb-faq-questions\">\t\t\t<span class=\"uagb-icon uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M432 256c0 17.69-14.33 32.01-32 32.01H256v144c0 17.69-14.33 31.99-32 31.99s-32-14.3-32-31.99v-144H48c-17.67 0-32-14.32-32-32.01s14.33-31.99 32-31.99H192v-144c0-17.69 14.33-32.01 32-32.01s32 14.32 32 32.01v144h144C417.7 224 432 238.3 432 256z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"uagb-icon-active uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M400 288h-352c-17.69 0-32-14.32-32-32.01s14.31-31.99 32-31.99h352c17.69 0 32 14.3 32 31.99S417.7 288 400 288z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t<span class=\"uagb-question\"><strong>MINIJOBBER Sch\u00fcler 16-17 Jahre  &#8211; (w\/m\/d) &#8211; 603-Euro-Basis<\/strong> <strong>Foodrunner<\/strong> <strong>ab sofort<\/strong><\/span><\/div><div class=\"uagb-faq-content\"><p><br><strong>Mit uns brauchst du kein Fitnessstudio \u2013 wir sorgen f\u00fcr deine Bewegung!<\/strong><br>Du hast neben Schule oder Studium noch etwas Zeit und suchst einen flexiblen Minijob in der Gastronomie?<br>Dann bist du bei uns genau richtig!<br>Werde Teil unseres Teams und unterst\u00fctze uns als Foodrunner (m\/w\/d) im Service.<br><br><strong>Das erwartet dich bei uns<\/strong><br>Arbeiten in einem motivierten, herzlichen und engagierten Team<br>Flexible Arbeitszeiten \u2013 wir nehmen R\u00fccksicht auf deine privaten Pl\u00e4ne<br>Moderner Arbeitsplatz mit neuester Technik<br>Unterst\u00fctzung durch Serviceroboter im Service<br>Mitarbeiterverpflegung zu fairen Konditionen<br>Ein abwechslungsreicher Job mit Bewegung und direktem G\u00e4stekontakt<br><br><strong>Das bringst du mit<\/strong><br>Freude am Umgang mit G\u00e4sten und ein freundliches Auftreten<br>Teamf\u00e4higkeit, Zuverl\u00e4ssigkeit und eine selbstst\u00e4ndige Arbeitsweise<br>Optional erste Erfahrung in der Gastronomie (kein Muss!)<br>Gute Deutschkenntnisse in Wort und Schrift<br>Grundkenntnisse in Englisch von Vorteil<br>Mindestalter: 16 Jahre<br><br><strong>Wichtig zu wissen<\/strong><br>Unser Betrieb ist ganzj\u00e4hrig ge\u00f6ffnet \u2013 auch an Sonn- und Feiertagen.<br>Daf\u00fcr erwarten wir Bereitschaft zur Mitarbeit an diesen Tagen.<br><br><strong>Jetzt bewerben<\/strong><br>Du hast Lust auf einen abwechslungsreichen Job mit Bewegung und Teamspirit?<br>Dann freuen wir uns auf deine Bewerbung per E-Mail oder Post!<br>\u00dcberzeuge uns \u2013 wir freuen uns auf dich!<br><br><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.uhrwerk-gutach.de\/wp-content\/uploads\/2021\/01\/Bild-Stellenanzeige-Restaurantkraft-Ersatzbild.png\" alt=\"Restaurantfachkraft\"><\/p><\/div><\/div><div class=\"wp-block-uagb-faq-child uagb-faq-child__outer-wrap uagb-faq-item uagb-block-16c7c0e8 \" role=\"tab\" tabindex=\"0\"><div class=\"uagb-faq-questions-button uagb-faq-questions\">\t\t\t<span class=\"uagb-icon uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M432 256c0 17.69-14.33 32.01-32 32.01H256v144c0 17.69-14.33 31.99-32 31.99s-32-14.3-32-31.99v-144H48c-17.67 0-32-14.32-32-32.01s14.33-31.99 32-31.99H192v-144c0-17.69 14.33-32.01 32-32.01s32 14.32 32 32.01v144h144C417.7 224 432 238.3 432 256z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"uagb-icon-active uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M400 288h-352c-17.69 0-32-14.32-32-32.01s14.31-31.99 32-31.99h352c17.69 0 32 14.3 32 31.99S417.7 288 400 288z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t<span class=\"uagb-question\"><strong>\u00dcBERBR\u00dcCKUNGSJAHR &#8211; f\u00fcr Abiturienten in Voll- und Teilzeit &#8211; Service &#8211; individuelle Dauer (6-12 Monate) &#8211; 2026<\/strong><\/span><\/div><div class=\"uagb-faq-content\"><p><strong>\u00dcberbr\u00fcckungsjob nach dem Abitur (m\/w\/d) \u2013 Vollzeit \/ Teilzeit<\/strong><br><strong>Nach der Schule noch nichts vor? Dann \u00fcberbr\u00fccke deine Zeit bis zum n\u00e4chsten Semester bei uns!<\/strong><br>Du hast dein Abitur in der Tasche und m\u00f6chtest die Zeit sinnvoll nutzen, Geld verdienen und erste Berufserfahrung in der Gastronomie sammeln?<br>Dann bist du bei uns genau richtig!<br>Wir bieten dir einen abwechslungsreichen Job in einem motivierten Team \u2013 perfekt als \u00dcberbr\u00fcckung bis Studium, Ausbildung oder Reise.<br><br><strong>Das erwartet dich bei uns<\/strong><br>Arbeiten in einem engagierten, freundlichen Team<br>Flexible Arbeitszeiten<br>Moderner Arbeitsplatz mit neuester Technik<br>\u00dcberdurchschnittliche Bezahlung<br>Mitarbeiterverpflegung zu kleinen Preisen<br>Raum f\u00fcr eigene Ideen und aktive Mitgestaltung<br>Ein spannender Job mit Einblick in die Gastronomie<br><br><strong>Das bringst du mit<\/strong><br>Erste Erfahrung in der Gastronomie (Service oder Theke) von Vorteil<br>Teamf\u00e4higkeit, Zuverl\u00e4ssigkeit und Kreativit\u00e4t<br>Freundliches und professionelles Auftreten gegen\u00fcber G\u00e4sten, Kollegen und Lieferanten<br>Selbstst\u00e4ndige und strukturierte Arbeitsweise<br>EDV-Kenntnisse (z. B. Tabletkasse, digitales Reservierungssystem)<br>Gute Deutschkenntnisse in Wort und Schrift<br>Grundkenntnisse in Englisch<br><br><strong>Wichtig zu wissen<\/strong><br>Unser Betrieb ist ganzj\u00e4hrig ge\u00f6ffnet \u2013 auch an Sonn- und Feiertagen.<br>Daf\u00fcr bieten wir dir einen fairen Freizeitausgleich, wenn andere arbeiten.<br><br><strong>Jetzt bewerben<\/strong><br>Du m\u00f6chtest die Zeit nach dem Abi sinnvoll nutzen und Teil unseres Teams werden?<br>Dann freuen wir uns auf deine Bewerbung per E-Mail oder Post!<br>\u00dcberzeuge uns mit deiner Pers\u00f6nlichkeit \u2013 wir freuen uns auf dich!<br><br><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.uhrwerk-gutach.de\/wp-content\/uploads\/2021\/01\/Bild-Stellenanzeige-Restaurantkraft-Ersatzbild.png\" alt=\"Restaurantfachkraft\"><\/p><\/div><\/div><div class=\"wp-block-uagb-faq-child uagb-faq-child__outer-wrap uagb-faq-item uagb-block-7e859e21 \" role=\"tab\" tabindex=\"0\"><div class=\"uagb-faq-questions-button uagb-faq-questions\">\t\t\t<span class=\"uagb-icon uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M432 256c0 17.69-14.33 32.01-32 32.01H256v144c0 17.69-14.33 31.99-32 31.99s-32-14.3-32-31.99v-144H48c-17.67 0-32-14.32-32-32.01s14.33-31.99 32-31.99H192v-144c0-17.69 14.33-32.01 32-32.01s32 14.32 32 32.01v144h144C417.7 224 432 238.3 432 256z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"uagb-icon-active uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M400 288h-352c-17.69 0-32-14.32-32-32.01s14.31-31.99 32-31.99h352c17.69 0 32 14.3 32 31.99S417.7 288 400 288z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t<span class=\"uagb-question\"><strong>AUSZUBILDENDE &#8211; als Fachkraft f\u00fcr Restaurants und Veranstaltungsgastronomie (w\/m\/d) zum 01.09.202<\/strong>7<\/span><\/div><div class=\"uagb-faq-content\"><p><br><strong>Wie viele Gl\u00e4ser kannst du balancieren? Finde es heraus als unser\/e Auszubildende\/r<strong> Fachkraft f\u00fcr Restaurants und Veranstaltungsgastronomie<\/strong>!<\/strong><br><br>Wir sind t\u00e4glich mit Feuereifer bei der Sache, lieben es Gastgeber zu sein und haben einen hohen Anspruch an uns selbst. Dabei ist uns wichtig, dass jeder, der Teil von unserem Team wird, Leidenschaft, Herzlichkeit, Anspruch und Echtheit lebt. Wir freuen uns, dich in unserem Team aufzunehmen und dir alles zu zeigen, damit auch du ein\/e gute\/r Gastgeber\/in wirst!<br><br><strong>Mehr als nur ein Ausbildungsplatz &#8211; das lernst du bei uns:<\/strong><br>&#8211; Bedienung und Bewirtung von G\u00e4sten, zuvorkommender Service steht dabei im Vordergrund<br>&#8211; Bedienung des Kassensystems<br>&#8211; Beratung der G\u00e4ste zum Essensangebot und die Auskunft zu verschiedenen Nahrungsmitteln und Getr\u00e4nken<br>&#8211; Zusammenstellung und Gestaltung von Speisekarten und Angeboten<br>&#8211; Beratung von Kunden bei der Planung ihrer Festlichkeiten und Veranstaltungen und deren Ausrichtung<br>&#8211; Vorbereitung und Dekoration von R\u00e4umlichkeiten und Einrichtungen<br>&#8211; Zubereitung kleinerer Speisen und Getr\u00e4nke<br>&#8211; F\u00fchrung der eigenen Station<br>&#8211; Organisation des eigenen Serviceablaufs<br><br><strong>Du wirst unsere Geheimzutat: &#8211; Das bringst du mit:<\/strong><br>&#8211; Mindestens Guter Hauptschulabschluss oder Mittlere Reife<br>&#8211; Gute Leistungen in Mathematik, Deutsch und Englisch<br>&#8211; Teamf\u00e4higkeit und Kreativit\u00e4t<br>&#8211; Organisationstalent<br>&#8211; Schnelle Auffassungsgabe und Verwantwortungsbewusstsein<br><br><strong>Was sonst noch wichtig ist:<\/strong><br>Wir sind ein Ganzjahresbetrieb mit Arbeit an Sonn- und Feiertagen. Du solltest bereit sein, dich hier mit einzubringen. Daf\u00fcr hast du frei, wenn andere arbeiten m\u00fcssen!<br>Nicht von hier? Wir unterst\u00fctzen dich gerne bei der Wohnungssuche!<br><br><strong>Das klingt echt gut?<\/strong><br>Dann \u00fcberzeuge uns mit deiner Bewerbung per Mail oder Post, dass du der\/die Beste f\u00fcr diesen Job bist!<br><br><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.uhrwerk-gutach.de\/wp-content\/uploads\/2021\/01\/Bild-Stellenanzeige-Azubi-Restaurantfachfrau.png\" alt=\"Portrait Restaurantleiterin\"><\/p><\/div><\/div><div class=\"wp-block-uagb-faq-child uagb-faq-child__outer-wrap uagb-faq-item uagb-block-8536acbe \" role=\"tab\" tabindex=\"0\"><div class=\"uagb-faq-questions-button uagb-faq-questions\">\t\t\t<span class=\"uagb-icon uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M432 256c0 17.69-14.33 32.01-32 32.01H256v144c0 17.69-14.33 31.99-32 31.99s-32-14.3-32-31.99v-144H48c-17.67 0-32-14.32-32-32.01s14.33-31.99 32-31.99H192v-144c0-17.69 14.33-32.01 32-32.01s32 14.32 32 32.01v144h144C417.7 224 432 238.3 432 256z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<span class=\"uagb-icon-active uagb-faq-icon-wrap\">\n\t\t\t\t\t\t\t\t<svg xmlns=\"https:\/\/www.w3.org\/2000\/svg\" viewBox= \"0 0 448 512\"><path d=\"M400 288h-352c-17.69 0-32-14.32-32-32.01s14.31-31.99 32-31.99h352c17.69 0 32 14.3 32 31.99S417.7 288 400 288z\"><\/path><\/svg>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t<span class=\"uagb-question\"><strong>AUSZUBILDENDER KOCH (w\/m\/d) zum 01.09.2027<\/strong><\/span><\/div><div class=\"uagb-faq-content\"><p><br><strong>Werde zum Lebensmittelk\u00fcnstler! Mach bei uns eine Ausbildung zum Koch (m\/w\/d)<\/strong><br><br>Wir lieben gutes Essen und du lernst dieses zuzubereiten!<br><br><strong>Mehr als nur ein Ausbildungsplatz &#8211; das lernst du bei uns:<\/strong><br>&#8211; Kochen, Braten, D\u00fcnsten, Flambieren, Marinieren, Garnieren und Filetieren<br>&#8211; Anrichten, Abschmecken und Arrangieren von Speisen<br>&#8211; Einkauf und fachgerechte Lagerung von Lebensmitteln<br>&#8211; Warenkunde, Qualit\u00e4tskontrolle, Kalkulation<br><br><strong>Du wirst unsere Geheimzutat: &#8211; Das bringst du mit:<\/strong><br>&#8211; Mindestens Guter Hauptschulabschluss oder Mittlere Reife<br>&#8211; Gute Leistungen in Mathematik, Deutsch und Englisch<br>&#8211; Teamf\u00e4higkeit und Kreativit\u00e4t<br>&#8211; Organisationstalent<br>&#8211; Schnelle Auffassungsgabe und Verwantwortungsbewusstsein<br>&#8211; Freude und Interesse an Arbeiten in der K\u00fcche<br><br><strong>Was sonst noch wichtig ist:<\/strong> <br>Wir sind ein Ganzjahresbetrieb mit Arbeit an Sonn- und Feiertagen. Du solltest bereit sein, dich hier mit einzubringen. Daf\u00fcr hast du frei, wenn andere arbeiten m\u00fcssen!<br>Nicht von hier? Wir unterst\u00fctzen dich gerne bei der Wohnungssuche!<br><br><strong>Das klingt echt gut?<\/strong><br>Dann \u00fcberzeuge uns mit deiner Bewerbung per Mail oder Post, dass du der\/die Beste f\u00fcr diesen Job bist!<br><br><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.uhrwerk-gutach.de\/wp-content\/uploads\/2021\/01\/Bild-Stellenanzeige-Koch.png\" alt=\"Koch beim Abschmecken\"><\/p><\/div><\/div><\/div>\n\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-2a2dcd7e alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<p class=\"wp-block-paragraph\">NICHTS PASSENDES DABEI?<\/p>\n\n\n\n<div class=\"wp-block-uagb-advanced-heading uagb-block-61b82159\"><h2 class=\"uagb-heading-text\">ERGREIFEN SIE DIE INITIATIVE!<\/h2><\/div>\n\n\n\n<div class=\"wp-block-uagb-separator uagb-block-ac83f154\"><div class=\"wp-block-uagb-separator__inner\" style=\"--my-background-image:\"><\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Auch ohne ein konkretes Stellenangebot haben Sie die M\u00f6glichkeit, sich initiativ bei uns zu bewerben. Wir freuen uns sehr auf Ihre Unterlagen.<br>Wir freuen uns auf Ihre Unterlagen per Mail unter:<br><a>info@webers-esszeit.de<\/a><\/p>\n\n\n\n<div class=\"wp-block-uagb-call-to-action uagb-block-00edb873 wp-block-button\"><div class=\"uagb-cta__wrap\"><p class=\"uagb-cta__desc\">Oder mit ein paar Klicks:<\/p><\/div><div class=\"uagb-cta__buttons\"><a href=\"https:\/\/uhrwerk-gutach.de\/webers-esszeit\/blitzbewerbung\/\" class=\"uagb-cta__button-link-wrapper wp-block-button__link\" target=\"_self\" rel=\"noopener noreferrer\">BLITZBEWERBUNG<\/a><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>STELLENANZEIGEN WERDEN SIE TEIL UNSERES TEAMS! NICHTS PASSENDES DABEI? ERGREIFEN SIE DIE INITIATIVE! Auch ohne ein konkretes Stellenangebot haben Sie die M\u00f6glichkeit, sich initiativ bei uns zu bewerben. Wir freuen uns sehr auf Ihre Unterlagen.Wir freuen uns auf Ihre Unterlagen per Mail unter:info@webers-esszeit.de<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-2953","page","type-page","status-publish","hentry"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/uhrwerk-gutach.de\/webers-esszeit\/author\/cweber\/"},"uagb_comment_info":0,"uagb_excerpt":"STELLENANZEIGEN WERDEN SIE TEIL UNSERES TEAMS! NICHTS PASSENDES DABEI? ERGREIFEN SIE DIE INITIATIVE! Auch ohne ein konkretes Stellenangebot haben Sie die M\u00f6glichkeit, sich initiativ bei uns zu bewerben. Wir freuen uns sehr auf Ihre Unterlagen.Wir freuen uns auf Ihre Unterlagen per Mail unter:info@webers-esszeit.de","_links":{"self":[{"href":"https:\/\/uhrwerk-gutach.de\/webers-esszeit\/wp-json\/wp\/v2\/pages\/2953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/uhrwerk-gutach.de\/webers-esszeit\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/uhrwerk-gutach.de\/webers-esszeit\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/uhrwerk-gutach.de\/webers-esszeit\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/uhrwerk-gutach.de\/webers-esszeit\/wp-json\/wp\/v2\/comments?post=2953"}],"version-history":[{"count":163,"href":"https:\/\/uhrwerk-gutach.de\/webers-esszeit\/wp-json\/wp\/v2\/pages\/2953\/revisions"}],"predecessor-version":[{"id":7222,"href":"https:\/\/uhrwerk-gutach.de\/webers-esszeit\/wp-json\/wp\/v2\/pages\/2953\/revisions\/7222"}],"wp:attachment":[{"href":"https:\/\/uhrwerk-gutach.de\/webers-esszeit\/wp-json\/wp\/v2\/media?parent=2953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}